{"id":11276,"date":"2020-03-20T07:28:07","date_gmt":"2020-03-20T07:28:07","guid":{"rendered":"https:\/\/tu11.fi\/taekwondo\/?p=11276"},"modified":"2020-04-26T01:22:23","modified_gmt":"2020-04-26T01:22:23","slug":"training-wahrend-und-nach-der-schliesung-des-fitnessstudios","status":"publish","type":"post","link":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/","title":{"rendered":"Training w\u00e4hrend und nach der Schlie\u00dfung des Fitnessstudios"},"content":{"rendered":"<h3>Taekwondo | Helsinki<\/h3>\n<h2><strong>Wir bieten Unterricht auch bei geschlossenem Saal an!<\/strong><\/h2>\n<p>Taekwondo-Sportler m\u00f6chte seinen Mitgliedern auch w\u00e4hrend der Schlie\u00dfung der Turnhalle Trainingsm\u00f6glichkeiten bieten. Dementsprechend werden wir umfangreiche Zusatzaktivit\u00e4ten organisieren, um die verlorene Trainingszeit auszugleichen, sobald wir wieder mit dem normalen Gruppentraining beginnen k\u00f6nnen.<\/p>\n<p>Bitte lesen Sie diese Nachricht sorgf\u00e4ltig durch, da sie viele Informationen und wertvolle Vorteile in dieser Ausnahmesituation enth\u00e4lt.<\/p>\n<h3><strong>Taekwondo-Athleten bieten virtuellen Unterricht an, wenn das Fitnessstudio geschlossen ist <\/strong><\/h3>\n<p>Virtuelle Kurse bieten Aktivit\u00e4ten bei geschlossenen Hallent\u00fcren an. Das Angebot ist vielf\u00e4ltig und reicht von Neben\u00fcbungen bis zum Sporttraining.<\/p>\n<p>Sie k\u00f6nnen es hier ansehen\u00a0<a href=\"https:\/\/tu11.fi\/taekwondo\/de\/virtuelle-klassen\/\">\u00fcber den Link &gt;&gt;<\/a>\u00a0oder indem Sie auf das Men\u00fc in der oberen rechten Ecke der Seite klicken.<\/p>\n<p>Alle, die die Schulungsgeb\u00fchr bezahlt haben, haben mit dem Newsletter ein Passwort erhalten. Wenn Sie Ihr Passwort nicht erhalten haben, kontaktieren Sie uns bitte\u00a0<a href=\"mailto:info@tu11.fi\">info@tu11.fi<\/a>.<\/p>\n<h3><strong>Training von Wettkampfmannschaften<\/strong><\/h3>\n<p>Begeisterte Wettkampfgruppen erhalten ein separates Trainingsprogramm, das es ihnen erm\u00f6glicht, auch zu Hause ein charakteristisches Training durchzuf\u00fchren.<\/p>\n<p>Sportler, die sich auf Wertwettk\u00e4mpfe vorbereiten, erhalten bei geschlossener Turnhalle gesonderte Trainingsanweisungen.<\/p>\n<h3><strong>Unterst\u00fctzen Sie die Aktivit\u00e4ten des Vereins in einer schwierigen Situation und zahlen Sie Ihre zuk\u00fcnftige Trainingsgeb\u00fchr im Voraus. Im Gegenzug bieten wir Schulungszeit in Ihrem Vertrag an! <\/strong><\/h3>\n<p>Die milden wirtschaftlichen Auswirkungen der Epidemie machen vielen Beteiligten zu schaffen, darunter auch Taekwondo-Sportlern. Der Vakka-Betrieb wird auf ein Minimum reduziert, die Fixkosten des Vereins wie Miete und Geh\u00e4lter bleiben wie bisher bestehen. W\u00e4hrend sich die Situation in die L\u00e4nge zieht, steht der Fortbestand des Vereins auf dem Spiel. Aus diesem Grund appellieren wir an alle, denen es \u00fcberhaupt m\u00f6glich ist, ihren Ausbildungsvertrag fortzusetzen und dem Verein durch diese schwierige Situation zu helfen. Um dies zu f\u00f6rdern, haben wir uns entschieden, die folgende Kampagne zu starten:<\/p>\n<ul>\n<li>Wenn Sie Ihre n\u00e4chste Vertragslaufzeit (3 Monate) bis Ende April bezahlen, erhalten Sie einen zus\u00e4tzlichen \u00dcbungsmonat kostenlos<\/li>\n<li>Durch die gleichzeitige Bezahlung von zwei Vertragssaisonen (6 Monate) verl\u00e4ngern wir den Ausbildungsvertrag um zwei zus\u00e4tzliche Monate<\/li>\n<\/ul>\n<p>Die Aktionen gelten automatisch f\u00fcr alle neuen 3-Monats-Zahlungszeitr\u00e4ume, die im M\u00e4rz oder April beginnen. Sollte Ihr Zahlungszeitraum erst nach diesem Zeitpunkt beginnen, k\u00f6nnen Sie von der Aktion profitieren, indem Sie Ihre Ausbildungszeit im Voraus bezahlen. Auch wenn Sie das 6-Monats-Angebot statt des 3-Monats-Angebots in Anspruch nehmen m\u00f6chten, m\u00fcssen Sie uns dies gesondert mitteilen.<\/p>\n<h2><strong>Training, wenn das Fitnessstudio wieder \u00f6ffnet<\/strong><\/h2>\n<p>Sobald es m\u00f6glich und vor allem sicher ist, werden wir zum normalen Ablauf zur\u00fcckkehren. Wir orientieren uns an den Vorschriften und Empfehlungen der Beh\u00f6rden, es kann sein, dass das Training am Anfang angewendet werden muss, z.B. durch die Betonung einzelner \u00dcbungen oder die Begrenzung der Gruppengr\u00f6\u00dfe.<\/p>\n<p>Wir m\u00f6chten jedoch im Voraus dar\u00fcber nachdenken, wie wir den Enthusiasten danken k\u00f6nnen, die ihre Trainingsgeb\u00fchren bezahlt haben, auch wenn wir nicht in der Lage waren, einen vollst\u00e4ndigen Service anzubieten.<\/p>\n<h3><strong>Zus\u00e4tzliche Lager <\/strong><\/h3>\n<p>F\u00fcr alle Enthusiasten, die die Trainingsgeb\u00fchr ununterbrochen bezahlt haben, organisieren wir ein paar kostenlose Extra-Camps.<\/p>\n<h3><strong>Dieses Jahr gibt es keine Sommerpause<\/strong><\/h3>\n<p>Diesen Sommer werden wir den ganzen Sommer \u00fcber trainieren, sofern es die Situation zu diesem Zeitpunkt nur zul\u00e4sst. Normalerweise haben wir die T\u00fcren des Fitnessstudios im Juli einige Wochen lang geschlossen gehalten, aber diesen Sommer werden wir auch \u00fcber diese Zeit hinaus weiter trainieren. Daher werden den ganzen Sommer \u00fcber \u00dcbungen f\u00fcr alle Altersgruppen angeboten<\/p>\n<h3><strong>Zusatzleistungen f\u00fcr alle Vertr\u00e4ge <\/strong><\/h3>\n<p>Allen, die ihre Ausbildungsgeb\u00fchr ohne Vertragsunterbrechung bezahlt haben, bieten wir konkrete Vorteile<\/p>\n<ul>\n<li>Grundvereinbarung f\u00fcr Erwachsene -&gt; Ein Monat Trainingsrecht f\u00fcr den Kraftraum<\/li>\n<li>Grundvertrag f\u00fcr Kinder -&gt; Ein Monat Trainingsrecht f\u00fcr die Kinder-Wettkampfmannschaft<\/li>\n<li>Vertrag f\u00fcr erwachsene Sportler -&gt; Ein Monat Training direkt im Kraftraum. Privatunterricht f\u00fcr diejenigen, die bereits einen Vertrag f\u00fcr das Fitnessstudio haben.<\/li>\n<li>Kindersportlervertrag -&gt; Kostenlose Privatstunde oder Lektion mit einem Paar, je nach Alter des Begeisterten.<\/li>\n<\/ul>\n<h3><strong>Die G\u00fcrtelpr\u00fcfungen im M\u00e4rz werden so bald wie m\u00f6glich stattfinden<\/strong><\/h3>\n<p>Die G\u00fcrtelpr\u00fcfungen im M\u00e4rz m\u00fcssen in die Zukunft verschoben werden. F\u00fcr die G\u00fcrtelpr\u00fcfungen liegen bereits Rechnungen vor, Sie melden sich also wie gewohnt durch die Bezahlung dieser Rechnung f\u00fcr die Pr\u00fcfung an <strong>Jetzt<\/strong>. Die G\u00fcrtelpr\u00fcfung wird durchgef\u00fchrt, sobald der normale Trainingsbetrieb wieder aufgenommen werden kann. Genauere Informationen zu den Tests werden wir den Teilnehmern zukommen lassen, sobald wir die Termine best\u00e4tigen k\u00f6nnen.<\/p>\n<p>Sollten Sie nicht an der Pr\u00fcfung teilnehmen, teilen Sie uns dies bitte zeitnah mit und wir erstatten Ihnen den Rechnungsbetrag.<\/p>\n<p>Vielen Dank f\u00fcr Ihre Unterst\u00fctzung und Ihr Verst\u00e4ndnis in dieser herausfordernden Zeit.<\/p>","protected":false},"excerpt":{"rendered":"<p>Taekwondo | Helsinki Wir bieten Unterricht auch dann an, wenn die Halle geschlossen ist! Taekwondo-Sportler m\u00f6chte seinen Mitgliedern auch w\u00e4hrend der Schlie\u00dfung des Fitnessstudios Trainingsm\u00f6glichkeiten bieten. Dementsprechend werden wir umfangreiche Zusatzaktivit\u00e4ten organisieren, um die verlorene Trainingszeit auszugleichen, sobald wir wieder mit dem normalen Gruppentraining beginnen k\u00f6nnen. Bitte lesen Sie diese Nachricht sorgf\u00e4ltig durch, denn sie enth\u00e4lt viele Informationen und wertvolle Vorteile in dieser Ausnahmesituation. Taekwondo-Athleten bieten virtuellen Unterricht an, wenn die Halle geschlossen ist. Virtuelle Kurse bieten...<\/p>","protected":false},"author":7,"featured_media":7667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"templates\/template-cover.php","format":"standard","meta":{"footnotes":""},"categories":[4,5,438,1],"tags":[],"class_list":["post-11276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etusivu","category-slider","category-uutiskirje","category-yleinen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Harjoittelu salin kiinniolon aikana ja sen j\u00e4lkeen - Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo | Vantaa<\/title>\n<meta name=\"description\" content=\"TU11 tarjoaa innostavan ymp\u00e4rist\u00f6n harjoitella taekwondoa kaikenik\u00e4isille ja -tasoisille, aloittelijoista huippu-urheilijoihin. Valmennus on systemaattista ja valmentajat maamme parhaimmistoa. Aloita taekwondo nyt!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/training-wahrend-und-nach-der-schliesung-des-fitnessstudios\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harjoittelu salin kiinniolon aikana ja sen j\u00e4lkeen - Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo | Vantaa","description":"TU11 bietet eine inspirierende Umgebung zum \u00dcben von Taekwondo f\u00fcr alle Altersgruppen und Leistungsniveaus, vom Anf\u00e4nger bis zum Spitzensportler. Das Training ist systematisch und die Trainer sind die besten unseres Landes. Beginnen Sie jetzt mit Taekwondo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/training-wahrend-und-nach-der-schliesung-des-fitnessstudios\/","schema":{"@context":"https:\/\/schema.org","@graph":[]}},"amp_enabled":true,"head":{"html":["<meta name=\"wpsso-begin\" content=\"wpsso structured data begin\"\/>\n","<!-- generator:1 --><meta name=\"generator\" content=\"WPSSO Core 22.0.0\/L*\"\/>\n","<!-- generator:2 --><meta name=\"generator\" content=\"WPSSO RAR 3.3.0\/S\"\/>\n","<!-- generator:3 --><meta name=\"generator\" content=\"WPSSO REST 3.3.0\/S\"\/>\n","<!-- generator:4 --><meta name=\"generator\" content=\"WPSSO BC 5.5.0\/S\"\/>\n","<!-- generator:5 --><meta name=\"generator\" content=\"WPSSO FAQ 7.1.0\/S\"\/>\n","<!-- generator:6 --><meta name=\"generator\" content=\"WPSSO OPM 5.1.0\/S\"\/>\n","<!-- generator:7 --><meta name=\"generator\" content=\"WPSSO SSM 3.4.0\/S\"\/>\n","<!-- generator:8 --><meta name=\"generator\" content=\"WPSSO TIE 4.1.0\/S\"\/>\n","<!-- generator:9 --><meta name=\"generator\" content=\"WPSSO UM 7.3.0\/S\"\/>\n","<!-- generator:10 --><meta name=\"generator\" content=\"WPSSO UL 4.3.0\/S\"\/>\n","<link rel=\"shortlink\" href=\"https:\/\/tu11.fi\/taekwondo\/de\/?p=11276\"\/>\n","<meta property=\"fb:app_id\" content=\"966242223397117\"\/>\n","<meta property=\"og:type\" content=\"article\"\/>\n","<meta property=\"og:url\" content=\"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\"\/>\n","<meta property=\"og:locale\" content=\"de_DE\"\/>\n","<meta property=\"og:site_name\" content=\"Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo | Vantaa\"\/>\n","<meta property=\"og:title\" content=\"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen  &ndash;...\"\/>\n","<meta property=\"og:description\" content=\"TU11 tarjoaa innostavan ymp&auml;rist&ouml;n harjoitella taekwondoa kaikenik&auml;isille ja -tasoisille, aloittelijoista huippu-urheilijoihin. Valmennus on systemaattista ja valmentajat maamme parhaimmistoa. Aloita taekwondo nyt!\"\/>\n","<meta property=\"og:updated_time\" content=\"2020-04-26T01:22:23+00:00\"\/>\n","<!-- og:image:1 --><meta property=\"og:image\" content=\"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg\"\/>\n","<!-- og:image:1 --><meta property=\"og:image:width\" content=\"1200\"\/>\n","<!-- og:image:1 --><meta property=\"og:image:height\" content=\"630\"\/>\n","<meta property=\"article:section\" content=\"Sport\"\/>\n","<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TU11\"\/>\n","<meta property=\"article:published_time\" content=\"2020-03-20T07:28:07+00:00\"\/>\n","<meta property=\"article:modified_time\" content=\"2020-04-26T01:22:23+00:00\"\/>\n","<meta name=\"twitter:domain\" content=\"tu11.fi\"\/>\n","<meta name=\"twitter:site\" content=\"@taekwondourh\"\/>\n","<meta name=\"twitter:title\" content=\"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen  &ndash;...\"\/>\n","<meta name=\"twitter:description\" content=\"TU11 tarjoaa innostavan ymp&auml;rist&ouml;n harjoitella taekwondoa kaikenik&auml;isille ja -tasoisille, aloittelijoista huippu-urheilijoihin. Valmennus on systemaattista ja valmentajat maamme parhaimmistoa...\"\/>\n","<meta name=\"twitter:card\" content=\"summary_large_image\"\/>\n","<meta name=\"twitter:image\" content=\"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg?p=11276\"\/>\n","<meta name=\"twitter:label1\" content=\"Written by\"\/>\n","<meta name=\"twitter:data1\" content=\"Pauli Raivio\"\/>\n","<meta name=\"twitter:label2\" content=\"Est. reading time\"\/>\n","<meta name=\"twitter:data2\" content=\"3 minutes\"\/>\n","<meta name=\"author\" content=\"Pauli Raivio\"\/>\n","<meta name=\"thumbnail\" content=\"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg\"\/>\n","<script type=\"application\/ld+json\" id=\"wpsso-schema-graph\">{\n    \"@context\": \"https:\/\/schema.org\",\n    \"@graph\": [\n        {\n            \"@id\": \"#sso\/knowledge-graph\/sports-team\/11276\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"SportsTeam\",\n            \"mainEntityOfPage\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\",\n            \"url\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\",\n            \"sameAs\": [\n                \"https:\/\/tu11.fi\/taekwondo\/de\/?p=11276\"\n            ],\n            \"name\": \"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen  &ndash;...\",\n            \"alternateName\": \"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa...\",\n            \"description\": \"TU11 tarjoaa innostavan ymp&auml;rist&ouml;n harjoitella taekwondoa kaikenik&auml;isille ja -tasoisille, aloittelijoista huippu-urheilijoihin. Valmennus on systemaattista ja valmentajat maamme parhaimmistoa. Aloita taekwondo nyt!\",\n            \"image\": [\n                {\n                    \"@id\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x1200-cropped.jpg#sso\/image-object\"\n                },\n                {\n                    \"@id\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x900-cropped.jpg#sso\/image-object\"\n                },\n                {\n                    \"@id\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x675-cropped.jpg#sso\/image-object\"\n                },\n                {\n                    \"@id\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg#sso\/image-object\"\n                }\n            ]\n        },\n        {\n            \"@id\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x1200-cropped.jpg#sso\/image-object\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"ImageObject\",\n            \"url\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x1200-cropped.jpg\",\n            \"identifier\": \"7667-wpsso-schema-1x1\",\n            \"name\": \"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa...\",\n            \"alternateName\": \"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo |...\",\n            \"description\": \"No Description.\",\n            \"encodingFormat\": \"image\/jpeg\",\n            \"uploadDate\": \"2018-03-31T11:18:21+00:00\",\n            \"width\": [\n                {\n                    \"@id\": \"#sso\/qv-width-px-1200\"\n                }\n            ],\n            \"height\": [\n                {\n                    \"@id\": \"#sso\/qv-height-px-1200\"\n                }\n            ]\n        },\n        {\n            \"@id\": \"#sso\/qv-width-px-1200\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"QuantitativeValue\",\n            \"name\": \"Width\",\n            \"unitText\": \"px\",\n            \"unitCode\": \"E37\",\n            \"value\": \"1200\"\n        },\n        {\n            \"@id\": \"#sso\/qv-height-px-1200\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"QuantitativeValue\",\n            \"name\": \"Height\",\n            \"unitText\": \"px\",\n            \"unitCode\": \"E37\",\n            \"value\": \"1200\"\n        },\n        {\n            \"@id\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x900-cropped.jpg#sso\/image-object\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"ImageObject\",\n            \"url\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x900-cropped.jpg\",\n            \"identifier\": \"7667-wpsso-schema-4x3\",\n            \"name\": \"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa...\",\n            \"alternateName\": \"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo |...\",\n            \"description\": \"No Description.\",\n            \"encodingFormat\": \"image\/jpeg\",\n            \"uploadDate\": \"2018-03-31T11:18:21+00:00\",\n            \"width\": [\n                {\n                    \"@id\": \"#sso\/qv-width-px-1200\"\n                }\n            ],\n            \"height\": [\n                {\n                    \"@id\": \"#sso\/qv-height-px-900\"\n                }\n            ]\n        },\n        {\n            \"@id\": \"#sso\/qv-height-px-900\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"QuantitativeValue\",\n            \"name\": \"Height\",\n            \"unitText\": \"px\",\n            \"unitCode\": \"E37\",\n            \"value\": \"900\"\n        },\n        {\n            \"@id\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x675-cropped.jpg#sso\/image-object\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"ImageObject\",\n            \"url\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x675-cropped.jpg\",\n            \"identifier\": \"7667-wpsso-schema-16x9\",\n            \"name\": \"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa...\",\n            \"alternateName\": \"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo |...\",\n            \"description\": \"No Description.\",\n            \"encodingFormat\": \"image\/jpeg\",\n            \"uploadDate\": \"2018-03-31T11:18:21+00:00\",\n            \"width\": [\n                {\n                    \"@id\": \"#sso\/qv-width-px-1200\"\n                }\n            ],\n            \"height\": [\n                {\n                    \"@id\": \"#sso\/qv-height-px-675\"\n                }\n            ]\n        },\n        {\n            \"@id\": \"#sso\/qv-height-px-675\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"QuantitativeValue\",\n            \"name\": \"Height\",\n            \"unitText\": \"px\",\n            \"unitCode\": \"E37\",\n            \"value\": \"675\"\n        },\n        {\n            \"@id\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg#sso\/image-object\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"ImageObject\",\n            \"url\": \"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg\",\n            \"identifier\": \"7667-wpsso-thumbnail\",\n            \"name\": \"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa...\",\n            \"alternateName\": \"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo |...\",\n            \"description\": \"No Description.\",\n            \"encodingFormat\": \"image\/jpeg\",\n            \"uploadDate\": \"2018-03-31T11:18:21+00:00\",\n            \"width\": [\n                {\n                    \"@id\": \"#sso\/qv-width-px-1200\"\n                }\n            ],\n            \"height\": [\n                {\n                    \"@id\": \"#sso\/qv-height-px-630\"\n                }\n            ]\n        },\n        {\n            \"@id\": \"#sso\/qv-height-px-630\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"QuantitativeValue\",\n            \"name\": \"Height\",\n            \"unitText\": \"px\",\n            \"unitCode\": \"E37\",\n            \"value\": \"630\"\n        },\n        {\n            \"@id\": \"\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/#sso\/breadcrumb.list\/etusivu\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"BreadcrumbList\",\n            \"url\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\",\n            \"itemListElement\": [\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 1,\n                    \"name\": \"Home\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 2,\n                    \"name\": \"Blog\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 3,\n                    \"name\": \"Etusivu Archives   Taekwondourheilijat 2011 | Taekwondoa parhaassa...\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/category\/etusivu\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 4,\n                    \"name\": \"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen...\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\"\n                }\n            ]\n        },\n        {\n            \"@id\": \"\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/#sso\/breadcrumb.list\/slider\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"BreadcrumbList\",\n            \"url\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\",\n            \"itemListElement\": [\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 1,\n                    \"name\": \"Home\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 2,\n                    \"name\": \"Blog\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 3,\n                    \"name\": \"slider Archives   Taekwondourheilijat 2011 | Taekwondoa parhaassa...\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/category\/slider\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 4,\n                    \"name\": \"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen...\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\"\n                }\n            ]\n        },\n        {\n            \"@id\": \"\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/#sso\/breadcrumb.list\/uutiskirje\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"BreadcrumbList\",\n            \"url\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\",\n            \"itemListElement\": [\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 1,\n                    \"name\": \"Home\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 2,\n                    \"name\": \"Blog\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 3,\n                    \"name\": \"Uutiskirje Archives   Taekwondourheilijat 2011 | Taekwondoa...\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/category\/uutiskirje\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 4,\n                    \"name\": \"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen...\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\"\n                }\n            ]\n        },\n        {\n            \"@id\": \"\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/#sso\/breadcrumb.list\/yleinen\",\n            \"@context\": \"https:\/\/schema.org\",\n            \"@type\": \"BreadcrumbList\",\n            \"url\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\",\n            \"itemListElement\": [\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 1,\n                    \"name\": \"Home\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 2,\n                    \"name\": \"Blog\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 3,\n                    \"name\": \"Yleinen Archives   Taekwondourheilijat 2011 | Taekwondoa parhaassa...\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/category\/yleinen\/\"\n                },\n                {\n                    \"@context\": \"https:\/\/schema.org\",\n                    \"@type\": \"ListItem\",\n                    \"position\": 4,\n                    \"name\": \"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen...\",\n                    \"item\": \"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/\"\n                }\n            ]\n        }\n    ]\n}<\/script>\n","<meta name=\"wpsso-end\" content=\"wpsso structured data end\"\/>\n","<meta name=\"wpsso-cached\" content=\"no cache for tu11.fi\/taekwondo\"\/>\n"],"json":[{"@context":"https:\/\/schema.org","@graph":[{"@id":"#sso\/knowledge-graph\/sports-team\/11276","@context":"https:\/\/schema.org","@type":"SportsTeam","mainEntityOfPage":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/","url":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/","sameAs":["https:\/\/tu11.fi\/taekwondo\/de\/?p=11276"],"name":"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen  &ndash;...","alternateName":"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa...","description":"TU11 tarjoaa innostavan ymp&auml;rist&ouml;n harjoitella taekwondoa kaikenik&auml;isille ja -tasoisille, aloittelijoista huippu-urheilijoihin. Valmennus on systemaattista ja valmentajat maamme parhaimmistoa. Aloita taekwondo nyt!","image":[{"@id":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x1200-cropped.jpg#sso\/image-object"},{"@id":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x900-cropped.jpg#sso\/image-object"},{"@id":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x675-cropped.jpg#sso\/image-object"},{"@id":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg#sso\/image-object"}]},{"@id":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x1200-cropped.jpg#sso\/image-object","@context":"https:\/\/schema.org","@type":"ImageObject","url":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x1200-cropped.jpg","identifier":"7667-wpsso-schema-1x1","name":"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa...","alternateName":"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo |...","description":"No Description.","encodingFormat":"image\/jpeg","uploadDate":"2018-03-31T11:18:21+00:00","width":[{"@id":"#sso\/qv-width-px-1200"}],"height":[{"@id":"#sso\/qv-height-px-1200"}]},{"@id":"#sso\/qv-width-px-1200","@context":"https:\/\/schema.org","@type":"QuantitativeValue","name":"Width","unitText":"px","unitCode":"E37","value":"1200"},{"@id":"#sso\/qv-height-px-1200","@context":"https:\/\/schema.org","@type":"QuantitativeValue","name":"Height","unitText":"px","unitCode":"E37","value":"1200"},{"@id":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x900-cropped.jpg#sso\/image-object","@context":"https:\/\/schema.org","@type":"ImageObject","url":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x900-cropped.jpg","identifier":"7667-wpsso-schema-4x3","name":"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa...","alternateName":"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo |...","description":"No Description.","encodingFormat":"image\/jpeg","uploadDate":"2018-03-31T11:18:21+00:00","width":[{"@id":"#sso\/qv-width-px-1200"}],"height":[{"@id":"#sso\/qv-height-px-900"}]},{"@id":"#sso\/qv-height-px-900","@context":"https:\/\/schema.org","@type":"QuantitativeValue","name":"Height","unitText":"px","unitCode":"E37","value":"900"},{"@id":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x675-cropped.jpg#sso\/image-object","@context":"https:\/\/schema.org","@type":"ImageObject","url":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x675-cropped.jpg","identifier":"7667-wpsso-schema-16x9","name":"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa...","alternateName":"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo |...","description":"No Description.","encodingFormat":"image\/jpeg","uploadDate":"2018-03-31T11:18:21+00:00","width":[{"@id":"#sso\/qv-width-px-1200"}],"height":[{"@id":"#sso\/qv-height-px-675"}]},{"@id":"#sso\/qv-height-px-675","@context":"https:\/\/schema.org","@type":"QuantitativeValue","name":"Height","unitText":"px","unitCode":"E37","value":"675"},{"@id":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg#sso\/image-object","@context":"https:\/\/schema.org","@type":"ImageObject","url":"https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg","identifier":"7667-wpsso-thumbnail","name":"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa...","alternateName":"38657901661_fa27cdaaa8_o  &ndash; Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo |...","description":"No Description.","encodingFormat":"image\/jpeg","uploadDate":"2018-03-31T11:18:21+00:00","width":[{"@id":"#sso\/qv-width-px-1200"}],"height":[{"@id":"#sso\/qv-height-px-630"}]},{"@id":"#sso\/qv-height-px-630","@context":"https:\/\/schema.org","@type":"QuantitativeValue","name":"Height","unitText":"px","unitCode":"E37","value":"630"},{"@id":"\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/#sso\/breadcrumb.list\/etusivu","@context":"https:\/\/schema.org","@type":"BreadcrumbList","url":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/","itemListElement":[{"@context":"https:\/\/schema.org","@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tu11.fi\/taekwondo\/de\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/tu11.fi\/taekwondo\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":3,"name":"Etusivu Archives   Taekwondourheilijat 2011 | Taekwondoa parhaassa...","item":"https:\/\/tu11.fi\/taekwondo\/de\/category\/etusivu\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":4,"name":"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen...","item":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/"}]},{"@id":"\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/#sso\/breadcrumb.list\/slider","@context":"https:\/\/schema.org","@type":"BreadcrumbList","url":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/","itemListElement":[{"@context":"https:\/\/schema.org","@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tu11.fi\/taekwondo\/de\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/tu11.fi\/taekwondo\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":3,"name":"slider Archives   Taekwondourheilijat 2011 | Taekwondoa parhaassa...","item":"https:\/\/tu11.fi\/taekwondo\/de\/category\/slider\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":4,"name":"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen...","item":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/"}]},{"@id":"\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/#sso\/breadcrumb.list\/uutiskirje","@context":"https:\/\/schema.org","@type":"BreadcrumbList","url":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/","itemListElement":[{"@context":"https:\/\/schema.org","@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tu11.fi\/taekwondo\/de\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/tu11.fi\/taekwondo\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":3,"name":"Uutiskirje Archives   Taekwondourheilijat 2011 | Taekwondoa...","item":"https:\/\/tu11.fi\/taekwondo\/de\/category\/uutiskirje\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":4,"name":"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen...","item":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/"}]},{"@id":"\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/#sso\/breadcrumb.list\/yleinen","@context":"https:\/\/schema.org","@type":"BreadcrumbList","url":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/","itemListElement":[{"@context":"https:\/\/schema.org","@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tu11.fi\/taekwondo\/de\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/tu11.fi\/taekwondo\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":3,"name":"Yleinen Archives   Taekwondourheilijat 2011 | Taekwondoa parhaassa...","item":"https:\/\/tu11.fi\/taekwondo\/de\/category\/yleinen\/"},{"@context":"https:\/\/schema.org","@type":"ListItem","position":4,"name":"Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen...","item":"https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/"}]}]}],"parts":[["meta","name","generator","content","WPSSO Core 22.0.0\/L*","generator:1"],["meta","name","generator","content","WPSSO RAR 3.3.0\/S","generator:2"],["meta","name","generator","content","WPSSO REST 3.3.0\/S","generator:3"],["meta","name","generator","content","WPSSO BC 5.5.0\/S","generator:4"],["meta","name","generator","content","WPSSO FAQ 7.1.0\/S","generator:5"],["meta","name","generator","content","WPSSO OPM 5.1.0\/S","generator:6"],["meta","name","generator","content","WPSSO SSM 3.4.0\/S","generator:7"],["meta","name","generator","content","WPSSO TIE 4.1.0\/S","generator:8"],["meta","name","generator","content","WPSSO UM 7.3.0\/S","generator:9"],["meta","name","generator","content","WPSSO UL 4.3.0\/S","generator:10"],["link","rel","shortlink","href","https:\/\/tu11.fi\/taekwondo\/de\/?p=11276",""],["meta","property","fb:app_id","content","966242223397117",""],["meta","property","og:time","content","2026-05-13T03:18:26+00:00",""],["meta","property","og:type","content","article",""],["meta","property","og:url","content","https:\/\/tu11.fi\/taekwondo\/de\/2020\/03\/harjoittelu-salin-kiinniolon-aikana-ja-sen-jalkeen\/",""],["meta","property","og:locale","content","de_DE",""],["meta","property","og:site_name","content","Taekwondourheilijat 2011 | Taekwondoa parhaassa seurassa | Helsinki | Espoo | Vantaa",""],["meta","property","og:title","content","Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen  &ndash;...",""],["meta","property","og:description","content","TU11 tarjoaa innostavan ymp&auml;rist&ouml;n harjoitella taekwondoa kaikenik&auml;isille ja -tasoisille, aloittelijoista huippu-urheilijoihin. Valmennus on systemaattista ja valmentajat maamme parhaimmistoa. Aloita taekwondo nyt!",""],["meta","property","og:updated_time","content","2020-04-26T01:22:23+00:00",""],["meta","property","og:image:secure_url","content","https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg","og:image:1"],["meta","property","og:image:url","content","https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg","og:image:1"],["meta","property","og:image","content","https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg","og:image:1"],["meta","property","og:image:width","content","1200","og:image:1"],["meta","property","og:image:height","content","630","og:image:1"],["meta","property","og:image:cropped","content","true","og:image:1"],["meta","property","og:image:id","content","7667","og:image:1"],["meta","property","og:image:size_name","content","wpsso-opengraph","og:image:1"],["meta","name","schema:language","content","de_DE",""],["meta","name","schema:type:id","content","sports.team",""],["meta","name","schema:type:url","content","https:\/\/schema.org\/SportsTeam",""],["meta","name","schema:type:context","content","https:\/\/schema.org",""],["meta","name","schema:type:name","content","SportsTeam",""],["meta","name","schema:type:path","content","schema.org\/SportsTeam",""],["meta","property","article:section","content","Sport",""],["meta","property","article:author:name","content","Pauli Raivio",""],["meta","property","article:publisher","content","https:\/\/www.facebook.com\/TU11",""],["meta","property","article:published_time","content","2020-03-20T07:28:07+00:00",""],["meta","property","article:modified_time","content","2020-04-26T01:22:23+00:00",""],["meta","property","article:reading_mins","content","3",""],["meta","name","twitter:domain","content","tu11.fi",""],["meta","name","twitter:site","content","@taekwondourh",""],["meta","name","twitter:title","content","Harjoittelu salin kiinniolon aikana ja sen j&auml;lkeen  &ndash;...",""],["meta","name","twitter:description","content","TU11 tarjoaa innostavan ymp&auml;rist&ouml;n harjoitella taekwondoa kaikenik&auml;isille ja -tasoisille, aloittelijoista huippu-urheilijoihin. Valmennus on systemaattista ja valmentajat maamme parhaimmistoa...",""],["meta","name","twitter:card","content","summary_large_image",""],["meta","name","twitter:image","content","https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg?p=11276",""],["meta","name","twitter:label1","content","Written by",""],["meta","name","twitter:data1","content","Pauli Raivio",""],["meta","name","twitter:label2","content","Est. reading time",""],["meta","name","twitter:data2","content","3 minutes",""],["meta","name","author","content","Pauli Raivio",""],["meta","name","thumbnail","content","https:\/\/tu11.fi\/taekwondo\/wp-content\/uploads\/2018\/03\/38657901661_fa27cdaaa8_o-3-1200x630-cropped.jpg",""]]},"_links":{"self":[{"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/posts\/11276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/comments?post=11276"}],"version-history":[{"count":0,"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/posts\/11276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/media\/7667"}],"wp:attachment":[{"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/media?parent=11276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/categories?post=11276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tu11.fi\/taekwondo\/de\/wp-json\/wp\/v2\/tags?post=11276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}